{"id":102636,"count":4,"description":"","link":"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/","name":"Bureau of Land Management","slug":"bureau-of-land-management","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bureau of Land Management Archives - Energy Exchange<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bureau of Land Management Archives - Energy Exchange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/\" \/>\n<meta property=\"og:site_name\" content=\"Energy Exchange\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/tag\\\/bureau-of-land-management\\\/\",\"url\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/tag\\\/bureau-of-land-management\\\/\",\"name\":\"Bureau of Land Management Archives - Energy Exchange\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/tag\\\/bureau-of-land-management\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/tag\\\/bureau-of-land-management\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bureau of Land Management\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/#website\",\"url\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/\",\"name\":\"Energy Exchange\",\"description\":\"Accelerating the clean energy revolution\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bureau of Land Management Archives - Energy Exchange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/","og_locale":"en_US","og_type":"article","og_title":"Bureau of Land Management Archives - Energy Exchange","og_url":"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/","og_site_name":"Energy Exchange","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/","url":"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/","name":"Bureau of Land Management Archives - Energy Exchange","isPartOf":{"@id":"https:\/\/blogs.edf.org\/energyexchange\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.edf.org\/energyexchange\/tag\/bureau-of-land-management\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.edf.org\/energyexchange\/"},{"@type":"ListItem","position":2,"name":"Bureau of Land Management"}]},{"@type":"WebSite","@id":"https:\/\/blogs.edf.org\/energyexchange\/#website","url":"https:\/\/blogs.edf.org\/energyexchange\/","name":"Energy Exchange","description":"Accelerating the clean energy revolution","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.edf.org\/energyexchange\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/tags\/102636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/posts?tags=102636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}