{"id":20406,"date":"2020-08-12T10:00:45","date_gmt":"2020-08-12T14:00:45","guid":{"rendered":"http:\/\/blogs.edf.org\/energyexchange\/?p=20406"},"modified":"2020-08-12T12:04:25","modified_gmt":"2020-08-12T16:04:25","slug":"puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente","status":"publish","type":"post","link":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/","title":{"rendered":"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente."},"content":{"rendered":"<p>Por <a href=\"https:\/\/www.edf.org\/people\/fred-krupp\">Fred Krupp<\/a>\u00a0 y <a href=\"https:\/\/www.sierraclub.org\/board-directors\/meet-board\">Ram\u00f3n Cruz<\/a>, presidente de Sierra Club<\/p>\n<p>Puerto Rico se encuentra en el medio de lo que ha sido la temporada de huracanes m\u00e1s activa de la que se tiene registro y la enfrenta con un sistema de energ\u00eda el\u00e9ctrica antiguo y poco fiable. Los apagones, cada vez m\u00e1s frecuentes, dejaron a m\u00e1s de 400.000 personas a oscuras antes de que la tormenta tropical Isa\u00edas tocara tierra en el territorio estadounidense la semana pasada. Isa\u00edas es la \u00faltima tormenta que ha puesto a prueba la preparaci\u00f3n de Puerto Rico despu\u00e9s de que el hurac\u00e1n Mar\u00eda destrozara su red el\u00e9ctrica en el 2017.<\/p>\n<p><!--more--><\/p>\n<p>La falta de fondos federales para la reconstrucci\u00f3n de infraestructura cr\u00edtica y la negligencia constante de la administraci\u00f3n Trump han elevado el riesgo de que la pr\u00f3xima tormenta cause sufrimiento humano y da\u00f1os inimaginables.<\/p>\n<p>Hay pocos lugares donde la desigualdad social, econ\u00f3mica y ambiental es tan palpable como en Puerto Rico. Apenas unos meses atr\u00e1s, una serie de terremotos en el suroeste de Puerto Rico caus\u00f3 apagones generalizados y dej\u00f3 a miles de personas sin hogar en Guayanilla y ciudades adyacentes. El coronavirus ha paralizado una econom\u00eda que ya estaba considerablemente debilitada. Urge la ayuda necesaria para aliviar la situaci\u00f3n.<\/p>\n<p>La energ\u00eda es vital para que los residentes de Puerto Rico puedan acceder a agua potable, alimentos y servicios de salud. Sin embargo, tres a\u00f1os despu\u00e9s del hurac\u00e1n Mar\u00eda, los trabajos de reconstrucci\u00f3n del sistema el\u00e9ctrico apenas han comenzado y los apagones son habituales. Las comunidades rurales siguen siendo las m\u00e1s afectadas.<\/p>\n<p>Complica a\u00fan m\u00e1s las cosas el precio que pagan los puertorrique\u00f1os por una energ\u00eda sucia y poco fiable debido a una infraestructura de energ\u00eda anticuada y centralizada. La mayor parte de la electricidad se genera en centrales el\u00e9ctricas antiguas que queman petr\u00f3leo y requieren importaciones costosas, y dicha electricidad luego se transporta mediante un sistema de suministro fr\u00e1gil y deteriorado. El dise\u00f1o deficiente, que depende en gran medida de los combustibles f\u00f3siles, aumenta los costos de electricidad, ya de por s\u00ed elevados, y aumenta tambi\u00e9n la contaminaci\u00f3n del aire que perjudica la salud de los habitantes.<\/p>\n<p>Las medidas necesarias para corregir d\u00e9cadas de desaciertos en Puerto Rico son muchas. Una de ellas es tener un sistema energ\u00e9tico fiable y resiliente creado para soportar un clima cada vez m\u00e1s vol\u00e1til. Pero \u00fanicamente ser resilientes no es suficiente. Puerto Rico merece un futuro m\u00e1s limpio que priorice a las familias y comunidades vulnerables para brindarles una energ\u00eda segura, asequible y confiable.<\/p>\n<p>Los l\u00edderes en Washington y en San Juan deben buscar soluciones que surjan de las comunidades en la isla, que con la pandemia son incluso m\u00e1s vulnerables que antes del hurac\u00e1n Mar\u00eda. Los legisladores pueden apoyarlas eliminando las barreras que mantienen un sistema centralizado y proporcionando incentivos para que las comunidades inviertan y desarrollen recursos distribuidos mediante el uso de energ\u00eda solar en los tejados y otras tecnolog\u00edas innovadoras.<\/p>\n<p>Si bien es evidente la necesidad de reinventar la red el\u00e9ctrica para que sirva mejor a todas las comunidades en la isla, hay antecedentes preocupantes de grupos de inter\u00e9s que representan grandes proyectos energ\u00e9ticos que se priorizan sobre el bien com\u00fan. La mayor\u00eda de las comunidades tienen pocas esperanzas de que la Autoridad de Energ\u00eda El\u00e9ctrica de Puerto Rico (AEE) responda a los reclamos generales a favor de una energ\u00eda asequible y producida localmente, como lo son la energ\u00eda solar en los tejados y la energ\u00eda comunitaria.<\/p>\n<p>Ahora la AEE tiene la posibilidad de implementar mejoras duraderas en la red el\u00e9ctrica a trav\u00e9s de su Plan Integrado de Recursos (PIR), una estrategia de 20 a\u00f1os sobre c\u00f3mo los servicios p\u00fablicos desarrollar\u00e1n los recursos energ\u00e9ticos. Lamentablemente, el proceso ha sufrido demoras y las modificaciones de la AEE no cumplen con la promesa del gobierno de generar el 40 % de la energ\u00eda mediante fuentes renovables para el 2025 y de que Puerto Rico supla el 100 % de la energ\u00eda a trav\u00e9s de fuentes renovables para el 2050.<\/p>\n<p>La AEE y los l\u00edderes electos de Puerto Rico deben dar prioridad a la transici\u00f3n energ\u00e9tica a largo plazo de la isla al escuchar activamente la opini\u00f3n de las partes interesadas, incluida la de las comunidades y las organizaciones no gubernamentales. Estos grupos han demostrado un liderazgo implacable para satisfacer las necesidades apremiantes en medio de sucesivas crisis y merecen nuestra atenci\u00f3n.<\/p>\n<p>Es fundamental que los funcionarios p\u00fablicos escuchen las inquietudes de las comunidades locales y su reclamo de descartar planes de construir nuevas centrales el\u00e9ctricas de gas natural que har\u00edan que Puerto Rico dependiera a\u00fan m\u00e1s de combustibles f\u00f3siles contaminantes, cuando las soluciones m\u00e1s limpias y centradas en la comunidad podr\u00edan marcar el rumbo futuro.<\/p>\n<p>Existen varias alternativas prometedoras para acelerar el crecimiento de la energ\u00eda limpia. Los recursos energ\u00e9ticos distribuidos a nivel comunitario, como la energ\u00eda solar e innovaciones recientes como las microrredes bajas en carbono (es decir, mini estaciones de servicio de energ\u00eda limpia que funcionan respaldadas por el almacenamiento de bater\u00eda), pueden ayudar a descentralizar y fortalecer la red.<\/p>\n<p>Un enfoque centrado en las prioridades de la comunidad es la \u00fanica manera de delinear el futuro energ\u00e9tico de Puerto Rico a fin de que \u00e9ste sirva a las personas, la econom\u00eda y el medioambiente de forma justa y equitativa. Sierra Club y el Fondo de Defensa Ambiental est\u00e1n trabajando junto a las comunidades y las organizaciones locales para impulsar el desarrollo de recursos energ\u00e9ticos distribuidos y beneficiarse de la resiliencia clim\u00e1tica que pueden brindar a la isla. La innovaci\u00f3n en materia de energ\u00eda limpia y el liderazgo comunitario son claves para lograr un sistema que pueda proteger a los residentes del archipi\u00e9lago en la pr\u00f3xima tormenta y mejore la calidad de vida de todos los puertorrique\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Fred Krupp\u00a0 y Ram\u00f3n Cruz, presidente de Sierra Club Puerto Rico se encuentra en el medio de lo que ha sido la temporada de huracanes m\u00e1s activa de la que se tiene registro y la enfrenta con un sistema de energ\u00eda el\u00e9ctrica antiguo y poco fiable. Los apagones, cada vez m\u00e1s frecuentes, dejaron a &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8015,42996,100446,84830,203],"tags":[106466],"coauthors":[],"class_list":["post-20406","post","type-post","status-publish","format-standard","hentry","category-air-quality","category-smart-power","category-energy-equity","category-grid-modernization","category-solar-energy","tag-puerto-rico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente. - Energy Exchange<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente. - Energy Exchange\" \/>\n<meta property=\"og:description\" content=\"Por Fred Krupp\u00a0 y Ram\u00f3n Cruz, presidente de Sierra Club Puerto Rico se encuentra en el medio de lo que ha sido la temporada de huracanes m\u00e1s activa de la que se tiene registro y la enfrenta con un sistema de energ\u00eda el\u00e9ctrica antiguo y poco fiable. Los apagones, cada vez m\u00e1s frecuentes, dejaron a ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Energy Exchange\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-12T14:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-12T16:04:25+00:00\" \/>\n<meta name=\"author\" content=\"EDF Blogs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"EDF Blogs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/2020\\\/08\\\/12\\\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/2020\\\/08\\\/12\\\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\\\/\"},\"author\":{\"name\":\"EDF Blogs\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/#\\\/schema\\\/person\\\/aae063915aaf10301a322185853c51d3\"},\"headline\":\"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente.\",\"datePublished\":\"2020-08-12T14:00:45+00:00\",\"dateModified\":\"2020-08-12T16:04:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/2020\\\/08\\\/12\\\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\\\/\"},\"wordCount\":1059,\"keywords\":[\"Puerto Rico\"],\"articleSection\":[\"Air Quality\",\"Clean Energy\",\"Energy Equity\",\"Grid Modernization\",\"Solar Energy\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/2020\\\/08\\\/12\\\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\\\/\",\"url\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/2020\\\/08\\\/12\\\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\\\/\",\"name\":\"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente. - Energy Exchange\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/#website\"},\"datePublished\":\"2020-08-12T14:00:45+00:00\",\"dateModified\":\"2020-08-12T16:04:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/#\\\/schema\\\/person\\\/aae063915aaf10301a322185853c51d3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/2020\\\/08\\\/12\\\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/2020\\\/08\\\/12\\\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/2020\\\/08\\\/12\\\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/#website\",\"url\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/\",\"name\":\"Energy Exchange\",\"description\":\"Accelerating the clean energy revolution\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/#\\\/schema\\\/person\\\/aae063915aaf10301a322185853c51d3\",\"name\":\"EDF Blogs\",\"description\":\"From time to time, the Energy Exchange blog includes posts from infrequent contributors, such as other EDF scientists and staff. Since these authors vary, we use this standard author bio profile for guest posts. For more information about this author, please see his\\\/her link at the beginning of the post.\",\"sameAs\":[\"https:\\\/\\\/www.edf.org\"],\"url\":\"https:\\\/\\\/blogs.edf.org\\\/energyexchange\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente. - Energy Exchange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/","og_locale":"en_US","og_type":"article","og_title":"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente. - Energy Exchange","og_description":"Por Fred Krupp\u00a0 y Ram\u00f3n Cruz, presidente de Sierra Club Puerto Rico se encuentra en el medio de lo que ha sido la temporada de huracanes m\u00e1s activa de la que se tiene registro y la enfrenta con un sistema de energ\u00eda el\u00e9ctrica antiguo y poco fiable. Los apagones, cada vez m\u00e1s frecuentes, dejaron a ...","og_url":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/","og_site_name":"Energy Exchange","article_published_time":"2020-08-12T14:00:45+00:00","article_modified_time":"2020-08-12T16:04:25+00:00","author":"EDF Blogs","twitter_card":"summary_large_image","twitter_misc":{"Written by":"EDF Blogs","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/#article","isPartOf":{"@id":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/"},"author":{"name":"EDF Blogs","@id":"https:\/\/blogs.edf.org\/energyexchange\/#\/schema\/person\/aae063915aaf10301a322185853c51d3"},"headline":"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente.","datePublished":"2020-08-12T14:00:45+00:00","dateModified":"2020-08-12T16:04:25+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/"},"wordCount":1059,"keywords":["Puerto Rico"],"articleSection":["Air Quality","Clean Energy","Energy Equity","Grid Modernization","Solar Energy"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/","url":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/","name":"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente. - Energy Exchange","isPartOf":{"@id":"https:\/\/blogs.edf.org\/energyexchange\/#website"},"datePublished":"2020-08-12T14:00:45+00:00","dateModified":"2020-08-12T16:04:25+00:00","author":{"@id":"https:\/\/blogs.edf.org\/energyexchange\/#\/schema\/person\/aae063915aaf10301a322185853c51d3"},"breadcrumb":{"@id":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.edf.org\/energyexchange\/2020\/08\/12\/puerto-rico-puede-tener-energia-limpia-fiable-y-equitativa-se-requiere-lo-siguiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.edf.org\/energyexchange\/"},{"@type":"ListItem","position":2,"name":"Puerto Rico puede tener energ\u00eda limpia, fiable y equitativa. Se requiere lo siguiente."}]},{"@type":"WebSite","@id":"https:\/\/blogs.edf.org\/energyexchange\/#website","url":"https:\/\/blogs.edf.org\/energyexchange\/","name":"Energy Exchange","description":"Accelerating the clean energy revolution","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.edf.org\/energyexchange\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blogs.edf.org\/energyexchange\/#\/schema\/person\/aae063915aaf10301a322185853c51d3","name":"EDF Blogs","description":"From time to time, the Energy Exchange blog includes posts from infrequent contributors, such as other EDF scientists and staff. Since these authors vary, we use this standard author bio profile for guest posts. For more information about this author, please see his\/her link at the beginning of the post.","sameAs":["https:\/\/www.edf.org"],"url":"https:\/\/blogs.edf.org\/energyexchange\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/posts\/20406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/comments?post=20406"}],"version-history":[{"count":0,"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/posts\/20406\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/media?parent=20406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/categories?post=20406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/tags?post=20406"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/blogs.edf.org\/energyexchange\/wp-json\/wp\/v2\/coauthors?post=20406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}